{"id":29694,"date":"2023-10-12T17:25:18","date_gmt":"2023-10-12T14:25:18","guid":{"rendered":"https:\/\/vinodeli.ee\/checkout\/"},"modified":"2023-12-08T11:55:52","modified_gmt":"2023-12-08T09:55:52","slug":"checkout","status":"publish","type":"page","link":"https:\/\/vinodeli.ee\/en\/checkout\/","title":{"rendered":"Checkout"},"content":{"rendered":"<div class=\"woocommerce\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-29694","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Checkout - Vinodeli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vinodeli.ee\/en\/checkout\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Checkout - Vinodeli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vinodeli.ee\/en\/checkout\/\" \/>\n<meta property=\"og:site_name\" content=\"Vinodeli\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-08T09:55:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/checkout\\\/\",\"url\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/checkout\\\/\",\"name\":\"Checkout - Vinodeli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/#website\"},\"datePublished\":\"2023-10-12T14:25:18+00:00\",\"dateModified\":\"2023-12-08T09:55:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/checkout\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vinodeli.ee\\\/en\\\/checkout\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/checkout\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Checkout\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/#website\",\"url\":\"https:\\\/\\\/vinodeli.ee\\\/\",\"name\":\"Vinodeli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vinodeli.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/#organization\",\"name\":\"Vinodeli O\u00dc\",\"url\":\"https:\\\/\\\/vinodeli.ee\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vinodeli.ee\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo-winodeli-1.png\",\"contentUrl\":\"https:\\\/\\\/vinodeli.ee\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo-winodeli-1.png\",\"width\":1500,\"height\":1150,\"caption\":\"Vinodeli O\u00dc\"},\"image\":{\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Checkout - Vinodeli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vinodeli.ee\/en\/checkout\/","og_locale":"en_US","og_type":"article","og_title":"Checkout - Vinodeli","og_url":"https:\/\/vinodeli.ee\/en\/checkout\/","og_site_name":"Vinodeli","article_modified_time":"2023-12-08T09:55:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vinodeli.ee\/en\/checkout\/","url":"https:\/\/vinodeli.ee\/en\/checkout\/","name":"Checkout - Vinodeli","isPartOf":{"@id":"https:\/\/vinodeli.ee\/#website"},"datePublished":"2023-10-12T14:25:18+00:00","dateModified":"2023-12-08T09:55:52+00:00","breadcrumb":{"@id":"https:\/\/vinodeli.ee\/en\/checkout\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vinodeli.ee\/en\/checkout\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vinodeli.ee\/en\/checkout\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vinodeli.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Checkout"}]},{"@type":"WebSite","@id":"https:\/\/vinodeli.ee\/#website","url":"https:\/\/vinodeli.ee\/","name":"Vinodeli","description":"","publisher":{"@id":"https:\/\/vinodeli.ee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vinodeli.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/vinodeli.ee\/#organization","name":"Vinodeli O\u00dc","url":"https:\/\/vinodeli.ee\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vinodeli.ee\/#\/schema\/logo\/image\/","url":"https:\/\/vinodeli.ee\/wp-content\/uploads\/2024\/02\/logo-winodeli-1.png","contentUrl":"https:\/\/vinodeli.ee\/wp-content\/uploads\/2024\/02\/logo-winodeli-1.png","width":1500,"height":1150,"caption":"Vinodeli O\u00dc"},"image":{"@id":"https:\/\/vinodeli.ee\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/pages\/29694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/comments?post=29694"}],"version-history":[{"count":0,"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/pages\/29694\/revisions"}],"wp:attachment":[{"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/media?parent=29694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}