{"id":47956,"date":"2021-06-19T17:38:40","date_gmt":"2021-06-19T14:38:40","guid":{"rendered":"https:\/\/vinodeli.ee\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/"},"modified":"2023-12-20T14:03:20","modified_gmt":"2023-12-20T12:03:20","slug":"brauneberger-juffer-sonnenuhr-riesling-spatlese-richter","status":"publish","type":"product","link":"https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/","title":{"rendered":"Brauneberger Juffer-Sonnenuhr Riesling Sp\u00e4tlese 2018 7.5%"},"content":{"rendered":"<p>Domineerivad valged virsikud, mirabelle-ploomid ja eksootilised puuviljad. V\u00e4ga tihe tekstuur, samas uskumatult elegantne ja rikkaliku peenusega. Tohutu aroomide rohkus on integreeritud keerulisse mineraalstruktuuri, mis raamistab selle erakordse hilise saagi.Fermentatsioon: Puidust t\u00fcnnidesLaagerdumine: Suur puidust t\u00fcnnides<em>Serveerimistemperatuur: 12\u00b0<\/em><em>Toidusoovitus: sobib aperitiiviks v\u00f5i v\u00e4rskete hooajaliste puuviljadega. Puuvilja-magus vein sobib suurep\u00e4raselt ka peene hallitus- ja pehme juustuga. Suurep\u00e4rane lisand praetud krevettide, tempura ja sashimi roogadele.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<blockquote><p>P\u00c4RITOLU: M\u00fclheim an der Mosel, Mosel, SaksamaaVeini t\u00fc\u00fcp: Saksa Predikaatvein &#8211; Sp\u00e4tlese (hilja korjatud marjadest valmistatud vein)Viinamarjasort: 100% RieslingAuhinnad: Wine Advocate, Robert Parker: 96-95Mosel Fine Wines, Jean Fisch &#038; David Rayer : 94: 92<\/p><\/blockquote>\n","protected":false},"featured_media":46310,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[19460],"product_tag":[],"class_list":{"0":"post-47956","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-white-wine","8":"first","9":"outofstock","10":"downloadable","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brauneberger Juffer-Sonnenuhr Riesling Sp\u00e4tlese 2018 7.5% - Vinodeli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brauneberger Juffer-Sonnenuhr Riesling Sp\u00e4tlese 2018 7.5% - Vinodeli\" \/>\n<meta property=\"og:description\" content=\"P\u00c4RITOLU: M\u00fclheim an der Mosel, Mosel, SaksamaaVeini t\u00fc\u00fcp: Saksa Predikaatvein - Sp\u00e4tlese (hilja korjatud marjadest valmistatud vein)Viinamarjasort: 100% RieslingAuhinnad: Wine Advocate, Robert Parker: 96-95Mosel Fine Wines, Jean Fisch &amp; David Rayer : 94: 92\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/\" \/>\n<meta property=\"og:site_name\" content=\"Vinodeli\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-20T12:03:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vinodeli.ee\/wp-content\/uploads\/2023\/11\/21q3w4e5ry-jpg-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/product\\\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\\\/\",\"url\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/product\\\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\\\/\",\"name\":\"Brauneberger Juffer-Sonnenuhr Riesling Sp\u00e4tlese 2018 7.5% - Vinodeli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/product\\\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/product\\\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vinodeli.ee\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/21q3w4e5ry-jpg-2.webp\",\"datePublished\":\"2021-06-19T14:38:40+00:00\",\"dateModified\":\"2023-12-20T12:03:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/product\\\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vinodeli.ee\\\/en\\\/product\\\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/product\\\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vinodeli.ee\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/21q3w4e5ry-jpg-2.webp\",\"contentUrl\":\"https:\\\/\\\/vinodeli.ee\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/21q3w4e5ry-jpg-2.webp\",\"width\":720,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/product\\\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vinodeli.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/vinodeli.ee\\\/pood\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Brauneberger Juffer-Sonnenuhr Riesling Sp\u00e4tlese 2018 7.5%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/#website\",\"url\":\"https:\\\/\\\/vinodeli.ee\\\/\",\"name\":\"Vinodeli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vinodeli.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/#organization\",\"name\":\"Vinodeli O\u00dc\",\"url\":\"https:\\\/\\\/vinodeli.ee\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vinodeli.ee\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo-winodeli-1.png\",\"contentUrl\":\"https:\\\/\\\/vinodeli.ee\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo-winodeli-1.png\",\"width\":1500,\"height\":1150,\"caption\":\"Vinodeli O\u00dc\"},\"image\":{\"@id\":\"https:\\\/\\\/vinodeli.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brauneberger Juffer-Sonnenuhr Riesling Sp\u00e4tlese 2018 7.5% - Vinodeli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/","og_locale":"en_US","og_type":"article","og_title":"Brauneberger Juffer-Sonnenuhr Riesling Sp\u00e4tlese 2018 7.5% - Vinodeli","og_description":"P\u00c4RITOLU: M\u00fclheim an der Mosel, Mosel, SaksamaaVeini t\u00fc\u00fcp: Saksa Predikaatvein - Sp\u00e4tlese (hilja korjatud marjadest valmistatud vein)Viinamarjasort: 100% RieslingAuhinnad: Wine Advocate, Robert Parker: 96-95Mosel Fine Wines, Jean Fisch & David Rayer : 94: 92","og_url":"https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/","og_site_name":"Vinodeli","article_modified_time":"2023-12-20T12:03:20+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/vinodeli.ee\/wp-content\/uploads\/2023\/11\/21q3w4e5ry-jpg-2.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/","url":"https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/","name":"Brauneberger Juffer-Sonnenuhr Riesling Sp\u00e4tlese 2018 7.5% - Vinodeli","isPartOf":{"@id":"https:\/\/vinodeli.ee\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/#primaryimage"},"image":{"@id":"https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/#primaryimage"},"thumbnailUrl":"https:\/\/vinodeli.ee\/wp-content\/uploads\/2023\/11\/21q3w4e5ry-jpg-2.webp","datePublished":"2021-06-19T14:38:40+00:00","dateModified":"2023-12-20T12:03:20+00:00","breadcrumb":{"@id":"https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/#primaryimage","url":"https:\/\/vinodeli.ee\/wp-content\/uploads\/2023\/11\/21q3w4e5ry-jpg-2.webp","contentUrl":"https:\/\/vinodeli.ee\/wp-content\/uploads\/2023\/11\/21q3w4e5ry-jpg-2.webp","width":720,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/vinodeli.ee\/en\/product\/brauneberger-juffer-sonnenuhr-riesling-spatlese-richter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vinodeli.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/vinodeli.ee\/pood\/"},{"@type":"ListItem","position":3,"name":"Brauneberger Juffer-Sonnenuhr Riesling Sp\u00e4tlese 2018 7.5%"}]},{"@type":"WebSite","@id":"https:\/\/vinodeli.ee\/#website","url":"https:\/\/vinodeli.ee\/","name":"Vinodeli","description":"","publisher":{"@id":"https:\/\/vinodeli.ee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vinodeli.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/vinodeli.ee\/#organization","name":"Vinodeli O\u00dc","url":"https:\/\/vinodeli.ee\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vinodeli.ee\/#\/schema\/logo\/image\/","url":"https:\/\/vinodeli.ee\/wp-content\/uploads\/2024\/02\/logo-winodeli-1.png","contentUrl":"https:\/\/vinodeli.ee\/wp-content\/uploads\/2024\/02\/logo-winodeli-1.png","width":1500,"height":1150,"caption":"Vinodeli O\u00dc"},"image":{"@id":"https:\/\/vinodeli.ee\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/product\/47956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/product\/47956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/media\/46310"}],"wp:attachment":[{"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/media?parent=47956"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/product_brand?post=47956"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/product_cat?post=47956"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vinodeli.ee\/en\/wp-json\/wp\/v2\/product_tag?post=47956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}